{"id":39177,"date":"2023-08-29T00:59:59","date_gmt":"2023-08-29T03:59:59","guid":{"rendered":"https:\/\/www.tembici.com.br\/?page_id=39177"},"modified":"2025-12-19T13:44:18","modified_gmt":"2025-12-19T16:44:18","slug":"belo-horizonte","status":"publish","type":"page","link":"https:\/\/www.tembici.com.br\/es\/belo-horizonte\/","title":{"rendered":"Belo Horizonte"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"39177\" class=\"elementor elementor-39177\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8d2be78 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8d2be78\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-91772ff\" data-id=\"91772ff\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4b7d29d7 elementor-widget elementor-widget-image\" data-id=\"4b7d29d7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.tembici.com.br\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"147\" height=\"30\" src=\"https:\/\/www.tembici.com.br\/wp-content\/uploads\/2023\/05\/Logo-Tembici.png\" class=\"attachment-large size-large wp-image-38821\" alt=\"\" srcset=\"https:\/\/www.tembici.com.br\/wp-content\/uploads\/2023\/05\/Logo-Tembici.png 147w, https:\/\/www.tembici.com.br\/wp-content\/uploads\/2023\/05\/Logo-Tembici-18x4.png 18w\" sizes=\"(max-width: 147px) 100vw, 147px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7d03a0c\" data-id=\"7d03a0c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0d04cab elementor-widget__width-initial elementor-widget elementor-widget-shortcode\" data-id=\"0d04cab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><div class=\"trp_language_switcher_shortcode\">\n<div class=\"trp-language-switcher trp-language-switcher-container\" data-no-translation >\n    <div class=\"trp-ls-shortcode-current-language\">\n        <a href=\"#\" class=\"trp-ls-shortcode-disabled-language trp-ls-disabled-language\" title=\"Espa\u00f1ol\" onclick=\"event.preventDefault()\">\n\t\t\t ES\t\t<\/a>\n    <\/div>\n    <div class=\"trp-ls-shortcode-language\">\n                <a href=\"#\" class=\"trp-ls-shortcode-disabled-language trp-ls-disabled-language\"  title=\"Espa\u00f1ol\" onclick=\"event.preventDefault()\">\n\t\t\t ES\t\t<\/a>\n                    <a href=\"https:\/\/www.tembici.com.br\/es\/wp-json\/wp\/v2\/pages\/39177#TRPLINKPROCESSED\" title=\"Portugu\u00eas do Brasil\">\n             PT        <\/a>\n\n            <a href=\"https:\/\/www.tembici.com.br\/es\/wp-json\/wp\/v2\/pages\/39177#TRPLINKPROCESSED\" title=\"English\">\n             EN        <\/a>\n\n        <\/div>\n    <script type=\"application\/javascript\">\n        \/\/ need to have the same with set from JS on both divs. Otherwise it can push stuff around in HTML\n        var trp_ls_shortcodes = document.querySelectorAll('.trp_language_switcher_shortcode .trp-language-switcher');\n        if ( trp_ls_shortcodes.length > 0) {\n            \/\/ get the last language switcher added\n            var trp_el = trp_ls_shortcodes[trp_ls_shortcodes.length - 1];\n\n            var trp_shortcode_language_item = trp_el.querySelector( '.trp-ls-shortcode-language' )\n            \/\/ set width\n            var trp_ls_shortcode_width                                               = trp_shortcode_language_item.offsetWidth + 16;\n            trp_shortcode_language_item.style.width                                  = trp_ls_shortcode_width + 'px';\n            trp_el.querySelector( '.trp-ls-shortcode-current-language' ).style.width = trp_ls_shortcode_width + 'px';\n\n            \/\/ We're putting this on display: none after we have its width.\n            trp_shortcode_language_item.style.display = 'none';\n        }\n    <\/script>\n<\/div>\n<\/div><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-61e1b928 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"61e1b928\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-23f5002a\" data-id=\"23f5002a\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1f28921e elementor-widget elementor-widget-heading\" data-id=\"1f28921e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Tembici e bike Est\u00e1cio agora est\u00e3o em Belo Horizonte! <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6a13672c elementor-widget elementor-widget-text-editor\" data-id=\"6a13672c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Est\u00e1cio: a faculdade que move voc\u00ea para todos os lados da cidade. Conecte-se com a energia e a liberdade que s\u00f3 a bike el\u00e9trica pode proporcionar.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-097a28f elementor-widget elementor-widget-text-editor\" data-id=\"097a28f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Para diversos trajetos do seu dia a dia, vai de bike Est\u00e1cio, vai de el\u00e9trica! Em Belo Horizonte todas as bikes s\u00e3o el\u00e9tricas, elas n\u00e3o possuem acelerador, voc\u00ea controla a velocidade ao simples pedalar.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-686354ec elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"686354ec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#planos\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Conhe\u00e7a os nossos planos<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c2d6201 elementor-view-stacked elementor-position-inline-start elementor-absolute elementor-hidden-tablet elementor-hidden-phone elementor-shape-circle elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"c2d6201\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"input4\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/api.whatsapp.com\/send?text=J%C3%A1%20viu%20que%20as%20bicis%20da%20Tembici%20chegaram%20em%20BH?%20Baixe%20o%20app%20Tembici%20para%20pedalar%20comigo:%20https:\/\/www.tembici.com.br\/pt\/belo-horizonte\/\" target=\"_blank\" class=\"elementor-icon elementor-animation-bob\" tabindex=\"-1\" aria-label=\"Compartilhe e n\u00e3o deixe seus amigos de fora\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-whatsapp\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"https:\/\/api.whatsapp.com\/send?text=J%C3%A1%20viu%20que%20as%20bicis%20da%20Tembici%20chegaram%20em%20BH?%20Baixe%20o%20app%20Tembici%20para%20pedalar%20comigo:%20https:\/\/www.tembici.com.br\/pt\/belo-horizonte\/\" target=\"_blank\" >\n\t\t\t\t\t\t\tCompartilhe e n\u00e3o deixe seus amigos de fora\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6c3a094f elementor-view-stacked elementor-position-inline-start elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-shape-circle elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"6c3a094f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/api.whatsapp.com\/send?text=J%C3%A1%20viu%20que%20as%20bicis%20da%20Tembici%20chegaram%20em%20Curitiba?%20Baixe%20o%20app%20Tembici%20para%20pedalar%20comigo:%20tembici.com.br\/pt\/curitiba\/\" target=\"_blank\" class=\"elementor-icon elementor-animation-bob\" tabindex=\"-1\" aria-label=\"Compartilhe e n\u00e3o deixe seus amigos de fora\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-whatsapp\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"https:\/\/api.whatsapp.com\/send?text=J%C3%A1%20viu%20que%20as%20bicis%20da%20Tembici%20chegaram%20em%20Curitiba?%20Baixe%20o%20app%20Tembici%20para%20pedalar%20comigo:%20tembici.com.br\/pt\/curitiba\/\" target=\"_blank\" >\n\t\t\t\t\t\t\tCompartilhe e n\u00e3o deixe seus amigos de fora\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-586f36b5 elementor-hidden-tablet elementor-hidden-phone\" data-id=\"586f36b5\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-55540df4 elementor-hidden-tablet elementor-hidden-phone elementor-widget elementor-widget-image\" data-id=\"55540df4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"763\" height=\"696\" src=\"https:\/\/www.tembici.com.br\/wp-content\/uploads\/2024\/02\/BH-Img-Banner-Superior.png\" class=\"attachment-large size-large wp-image-40117\" alt=\"\" srcset=\"https:\/\/www.tembici.com.br\/wp-content\/uploads\/2024\/02\/BH-Img-Banner-Superior.png 763w, https:\/\/www.tembici.com.br\/wp-content\/uploads\/2024\/02\/BH-Img-Banner-Superior-300x274.png 300w, https:\/\/www.tembici.com.br\/wp-content\/uploads\/2024\/02\/BH-Img-Banner-Superior-13x12.png 13w\" sizes=\"(max-width: 763px) 100vw, 763px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2c99a1ab elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2c99a1ab\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-304d9d05 elementor-hidden-desktop\" data-id=\"304d9d05\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-327a6f2a elementor-hidden-desktop elementor-widget elementor-widget-image\" data-id=\"327a6f2a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"763\" height=\"696\" src=\"https:\/\/www.tembici.com.br\/wp-content\/uploads\/2024\/02\/BH-Img-Banner-Superior.png\" class=\"attachment-large size-large wp-image-40117\" alt=\"\" srcset=\"https:\/\/www.tembici.com.br\/wp-content\/uploads\/2024\/02\/BH-Img-Banner-Superior.png 763w, https:\/\/www.tembici.com.br\/wp-content\/uploads\/2024\/02\/BH-Img-Banner-Superior-300x274.png 300w, https:\/\/www.tembici.com.br\/wp-content\/uploads\/2024\/02\/BH-Img-Banner-Superior-13x12.png 13w\" sizes=\"(max-width: 763px) 100vw, 763px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-48f6c638 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"48f6c638\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-27484ec3\" data-id=\"27484ec3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-277e258c elementor-widget elementor-widget-heading\" data-id=\"277e258c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Com bike Est\u00e1cio, Belo Horizonte fica mais perto de voc\u00ea.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9a30c1a elementor-widget elementor-widget-text-editor\" data-id=\"9a30c1a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Escolha o plano que combina com voc\u00ea e pague no cr\u00e9dito ou d\u00e9bito pelo aplicativo Tembici;<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bc71b0b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bc71b0b\" data-element_type=\"section\" data-e-type=\"section\" id=\"planos\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-56928a67\" data-id=\"56928a67\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-44e47da3 elementor-widget__width-initial eael-pricing-content-align-center eael-pricing-button-align-center elementor-widget elementor-widget-eael-pricing-table\" data-id=\"44e47da3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"eael-pricing-table.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t    <div class=\"eael-pricing style-1 eael-header-devider\">\n                    <div class=\"eael-pricing-item \">\n                <div class=\"header\">\n                                        <h2 class=\"title\">Avulso<\/h2>\n                <\/div>\n                <div class=\"eael-pricing-tag\">\n                    <span class=\"price-tag\"><span class=\"original-price\"><span class=\"price-currency\">R$<\/span>8,90<\/span><\/span><span class=\"price-period\">\/dia<\/span>                <\/div>\n                <div class=\"body\">\n                            <ul>\n                            <li class=\"eael-pricing-item-feature elementor-repeater-item-b078d47\">\n                    \n                                <span class=\"li-icon\">\n                <i aria-hidden=\"true\" class=\"fas fa-biking\"><\/i>            <\/span>\n\n        \n                    <span >Fa\u00e7a uma viagem \u00fanica de at\u00e9 15 minutos. <\/span>\n                    \n                     \n                <\/li>\n                            <li class=\"eael-pricing-item-feature elementor-repeater-item-9eee83c\">\n                    \n                                <span class=\"li-icon\">\n                <i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i>            <\/span>\n\n        \n                    <span >Ap\u00f3s a compra do plano, voc\u00ea tem at\u00e9 24h para iniciar a viagem.<\/span>\n                    \n                     \n                <\/li>\n                            <li class=\"eael-pricing-item-feature elementor-repeater-item-88c6215\">\n                    \n                                <span class=\"li-icon\">\n                <i aria-hidden=\"true\" class=\"far fa-clock\"><\/i>            <\/span>\n\n        \n                    <span >Passou dos 15 minutos?\u00a0 Pague R$0,90 a cada 1 minuto(s) a mais pedalados.<\/span>\n                    \n                     \n                <\/li>\n                            <li class=\"eael-pricing-item-feature elementor-repeater-item-135b6c4\">\n                    \n                                <span class=\"li-icon\">\n                <i aria-hidden=\"true\" class=\"fas fa-credit-card\"><\/i>            <\/span>\n\n        \n                    <span >Al\u00e9m do valor do plano, ser\u00e1 feita uma reten\u00e7\u00e3o tempor\u00e1ria no seu cart\u00e3o de cr\u00e9dito de R$20,00. O valor garante saldo para poss\u00edveis excedentes nas viagens, e ser\u00e1 mantido por at\u00e9 7 dias.<\/span>\n                    \n                     \n                <\/li>\n                            <li class=\"eael-pricing-item-feature elementor-repeater-item-5bfa7a8\">\n                    \n                                <span class=\"li-icon\">\n                <i aria-hidden=\"true\" class=\"fas fa-money-bill\"><\/i>            <\/span>\n\n        \n                    <span >Se os minutos adicionais da sua viagem ultrapassarem os R$20,00 retidos, a diferen\u00e7a ser\u00e1 cobrada automaticamente. Caso contr\u00e1rio, em at\u00e9 7 dias, o valor ser\u00e1 devolvido integral ou parcialmente, dependendo do total gasto na viagem.<\/span>\n                    \n                     \n                <\/li>\n                    <\/ul>\n                    <\/div>\n                                <div class=\"footer\">\n                    <a class=\"eael-pricing-button\" href=\"https:\/\/tembici.onelink.me\/qcBR\/46ms4qsc\" >\n                                                                                Comprar no app                                            <\/a>\n                <\/div>\n                            <\/div>\n                    <\/div>\n    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-7f7244e\" data-id=\"7f7244e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ac37f4e elementor-widget__width-initial eael-pricing-content-align-center eael-pricing-button-align-center elementor-widget elementor-widget-eael-pricing-table\" data-id=\"ac37f4e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"eael-pricing-table.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t    <div class=\"eael-pricing style-1 eael-header-devider\">\n                    <div class=\"eael-pricing-item \">\n                <div class=\"header\">\n                                        <h2 class=\"title\">Mensal<\/h2>\n                <\/div>\n                <div class=\"eael-pricing-tag\">\n                    <span class=\"price-tag\"><span class=\"original-price\"><span class=\"price-currency\">R$<\/span>32,90<\/span><\/span><span class=\"price-period\">\/m\u00eas<\/span>                <\/div>\n                <div class=\"body\">\n                            <ul>\n                            <li class=\"eael-pricing-item-feature elementor-repeater-item-b078d47\">\n                    \n                                <span class=\"li-icon\">\n                <i aria-hidden=\"true\" class=\"fas fa-biking\"><\/i>            <\/span>\n\n        \n                    <span >Pedale todos os dias! Fa\u00e7a at\u00e9 4 viagens por dia. Em cada viagem aproveita at\u00e9 30 minutos de pedal. <\/span>\n                    \n                     \n                <\/li>\n                            <li class=\"eael-pricing-item-feature elementor-repeater-item-326992b\">\n                    \n                                <span class=\"li-icon\">\n                <i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i>            <\/span>\n\n        \n                    <span >Pedalou mais? Nas viagens inclu\u00eddas no seu plano cada minuto extra custa R$0,40. Viagens adicionais custam R$8,90 cada.<\/span>\n                    \n                     \n                <\/li>\n                            <li class=\"eael-pricing-item-feature elementor-repeater-item-30d2202\">\n                    \n                                <span class=\"li-icon\">\n                <i aria-hidden=\"true\" class=\"fas fa-sync\"><\/i>            <\/span>\n\n        \n                    <span >Este \u00e9 um plano recorrente, renovado a cada 30 dias para manter voc\u00ea sempre em movimento.<\/span>\n                    \n                     \n                <\/li>\n                    <\/ul>\n                    <\/div>\n                                <div class=\"footer\">\n                    <a class=\"eael-pricing-button\" href=\"https:\/\/tembici.onelink.me\/qcBR\/46ms4qsc\" >\n                                                                                Comprar no app                                            <\/a>\n                <\/div>\n                            <\/div>\n                    <\/div>\n    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-81a6699\" data-id=\"81a6699\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d1a31fe elementor-widget__width-initial eael-pricing-content-align-center eael-pricing-button-align-center elementor-widget elementor-widget-eael-pricing-table\" data-id=\"d1a31fe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"eael-pricing-table.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t    <div class=\"eael-pricing style-1 eael-header-devider\">\n                    <div class=\"eael-pricing-item \">\n                <div class=\"header\">\n                                        <h2 class=\"title\">Anual<\/h2>\n                <\/div>\n                <div class=\"eael-pricing-tag\">\n                    <span class=\"price-tag\"><span class=\"original-price\"><span class=\"price-currency\">R$<\/span>281,90<\/span><\/span><span class=\"price-period\">\/ano<\/span>                <\/div>\n                <div class=\"body\">\n                            <ul>\n                            <li class=\"eael-pricing-item-feature elementor-repeater-item-b078d47\">\n                    \n                                <span class=\"li-icon\">\n                <i aria-hidden=\"true\" class=\"fas fa-biking\"><\/i>            <\/span>\n\n        \n                    <span >Pedale todos os dias! Fa\u00e7a at\u00e9 4 viagens por dia. Em cada viagem aproveita at\u00e9 1h de pedal. <\/span>\n                    \n                     \n                <\/li>\n                            <li class=\"eael-pricing-item-feature elementor-repeater-item-326992b\">\n                    \n                                <span class=\"li-icon\">\n                <i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i>            <\/span>\n\n        \n                    <span >Pedalou mais? Nas viagens inclu\u00eddas no seu plano cada minuto extra custa R$0,40. Viagens adicionais custam R$8,90 cada.<\/span>\n                    \n                     \n                <\/li>\n                            <li class=\"eael-pricing-item-feature elementor-repeater-item-30d2202\">\n                    \n                                <span class=\"li-icon\">\n                <i aria-hidden=\"true\" class=\"fas fa-sync\"><\/i>            <\/span>\n\n        \n                    <span >Este \u00e9 um plano recorrente, renovado anualmente para manter voc\u00ea sempre em movimento.<\/span>\n                    \n                     \n                <\/li>\n                    <\/ul>\n                    <\/div>\n                                <div class=\"footer\">\n                    <a class=\"eael-pricing-button\" href=\"https:\/\/tembici.onelink.me\/qcBR\/46ms4qsc\" >\n                                                                                Comprar no app                                            <\/a>\n                <\/div>\n                            <\/div>\n                    <\/div>\n    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-371eb906 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"371eb906\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-4edb6ff6\" data-id=\"4edb6ff6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-582e0e21 elementor-widget elementor-widget-heading\" data-id=\"582e0e21\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\nSinta a experi\u00eancia <br>\u00fanica de pedalar com tecnologia.\n\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9f292b6 elementor-widget elementor-widget-text-editor\" data-id=\"9f292b6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-start=\"201\" data-end=\"399\">O maior sistema de bikes compartilhadas da Am\u00e9rica Latina j\u00e1 faz parte da paisagem de <strong>Belo Horizonte<\/strong>.<\/p><p data-start=\"401\" data-end=\"494\">S\u00e3o <span style=\"color: #144bc8;\">51 esta\u00e7\u00f5es e 500 bicicletas<\/span>\u00a0para transformar sua mobilidade com praticidade e seguran\u00e7a.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-287a8d5e\" data-id=\"287a8d5e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-22d1f268 eael-infobox-content-align--left elementor-widget elementor-widget-eael-info-box\" data-id=\"22d1f268\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"eael-info-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"eael-infobox icon-on-top\">\n\t            <div class=\"infobox-content\">\n        <div><p><span style=\"font-size: 55px;color: #0045dd\">51<\/span><\/p><p>Esta\u00e7\u00f5es*<\/p><\/div>        <\/div>\n            <\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-27b06f4c\" data-id=\"27b06f4c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-baca4db eael-infobox-content-align--left elementor-widget elementor-widget-eael-info-box\" data-id=\"baca4db\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"eael-info-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"eael-infobox icon-on-top\">\n\t            <div class=\"infobox-content\">\n        <div><p><span style=\"font-size: 55px;color: #0045dd\">500\u00a0<\/span><\/p><p>Bikes el\u00e9tricas*<\/p><\/div>        <\/div>\n            <\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-19157204\" data-id=\"19157204\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-354880aa elementor-hidden-desktop elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"354880aa\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-56314422\" data-id=\"56314422\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-21d7330a elementor-widget elementor-widget-heading\" data-id=\"21d7330a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Bicicletas de qualidade internacional dispon\u00edveis sempre que quiser! <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1f0cbf6f elementor-widget elementor-widget-text-editor\" data-id=\"1f0cbf6f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Conhe\u00e7a mais sobre nossa bici.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2e964268 elementor-widget elementor-widget-image\" data-id=\"2e964268\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"740\" height=\"583\" src=\"https:\/\/www.tembici.com.br\/wp-content\/uploads\/2023\/11\/Bike-Mobile-BH.png\" class=\"attachment-large size-large wp-image-39443\" alt=\"\" srcset=\"https:\/\/www.tembici.com.br\/wp-content\/uploads\/2023\/11\/Bike-Mobile-BH.png 740w, https:\/\/www.tembici.com.br\/wp-content\/uploads\/2023\/11\/Bike-Mobile-BH-300x236.png 300w, https:\/\/www.tembici.com.br\/wp-content\/uploads\/2023\/11\/Bike-Mobile-BH-15x12.png 15w\" sizes=\"(max-width: 740px) 100vw, 740px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6dab1dd elementor-hidden-desktop elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6dab1dd\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-033fa82\" data-id=\"033fa82\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8c1f8bc elementor-widget elementor-widget-html\" data-id=\"8c1f8bc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<style>\r\n    .slick-slider .element {\r\n        min-height: 216px;\r\n        max-height: 216px;\r\n        padding: 15px;\r\n        border-radius: 10px;\r\n        -webkit-box-shadow: 0 0 7px rgba(0, 0, 0, .36);\r\n        box-shadow: 0 0 7px rgba(0, 0, 0, .36);\r\n        background-color: #fff;\r\n        line-height: 24px;\r\n        height: auto;\r\n        width: 100px;\r\n        color: #000;\r\n        display: inline-block;\r\n        margin: 23px 10px;\r\n        justify-content: center;\r\n        align-items: center;\r\n        font-size: 20px;\r\n    }\r\n    .slick-slider .slick-disabled {\r\n      opacity : 0; \r\n      pointer-events:none;\r\n    }\r\n    .numero {\r\n        margin-bottom: -14px;\r\n        height: 30px;\r\n        font-size: 15px;\r\n        border: 1px solid #144BC8;\r\n        border-radius: 32px;\r\n        padding-bottom: 14px;\r\n        padding-top: 14px;\r\n        display: flex;\r\n        width: 30px;\r\n        flex-direction: column;\r\n        flex-wrap: nowrap;\r\n        align-content: center;\r\n        justify-content: center;\r\n        align-items: center;\r\n    }\r\n    .slick-slider h4{\r\n      font-size: 18px;\r\n        margin-bottom: 0;\r\n    }\r\n    .slick-slider p{\r\n      margin: 0;\r\n        padding: 0;\r\n        font-size: 14px;\r\n    }\r\n    <\/style>\r\n    <link rel=\"stylesheet\" href=\"https:\/\/cdnjs.cloudflare.com\/ajax\/libs\/normalize\/5.0.0\/normalize.min.css\">\r\n    <link rel='stylesheet' href='https:\/\/cdn.jsdelivr.net\/npm\/slick-carousel@1.8.1\/slick\/slick.css'>\r\n    \r\n    <\/head>\r\n    <body>\r\n    <!-- partial:index.partial.html -->\r\n    <div class=\"slick-slider\">\r\n      <div class=\"element element-1\">\r\n        <div class=\"bike__caixa-mobile\">\r\n          <div class=\"numero\"><span>1<\/span><\/div>\r\n          <h4>Seguran\u00e7a <\/h4>\r\n          <p>Veja e seja visto com as lanternas de LED que acendem conforme voc\u00ea pedala.<\/p>\r\n          \r\n    \r\n      <\/div>\r\n      <\/div>\r\n      <div class=\"element element-2\">\r\n        <div class=\"bike__caixa-mobile\">\r\n          <div class=\"numero\"><span>2<\/span><\/div>\r\n         \r\n        <h4>Pot\u00eancia<\/h4>\r\n          <p>Comece a pedalar e conte com o motor da bicicleta para uma dose extra de energia.<\/p>\r\n    \r\n      <\/div>\r\n      <\/div>\r\n      <div class=\"element element-3\">\r\n        <div class=\"bike__caixa-mobile\" data-hash=\"conforto\">\r\n          <div class=\"numero\"><span>3<\/span><\/div>\r\n          <h4>Conforto<\/h4>\r\n          <p>Transporte at\u00e9 5kg no cesto com el\u00e1stico ajust\u00e1vel.\r\n  \r\n        <\/p>\r\n          \r\n    \r\n      <\/div>\r\n      <\/div>\r\n      <div class=\"element element-4\">\r\n        <div class=\"bike__caixa-mobile\">\r\n          <div class=\"numero\"><span>4<\/span><\/div>\r\n          <h4>Seguran\u00e7a<\/h4>\r\n          <p>Sistema antivandalismo e localizado com GPS.<\/p>\r\n         \r\n    \r\n      <\/div>\r\n      <\/div>\r\n      <div class=\"element element-5\">\r\n        <div class=\"bike__caixa-mobile\">\r\n          <div class=\"numero\"><span>5<\/span><\/div>\r\n          <h4>Praticidade<\/h4>\r\n          <p>Desbloqueie uma bicicleta com um QR Code ou atrav\u00e9s do aplicativo.\r\n        <\/p>\r\n         \r\n    \r\n      <\/div>\r\n      <\/div>\r\n  \r\n      <div class=\"element element-6\">\r\n        \r\n          <div class=\"bike__caixa-mobile\">\r\n              <div class=\"numero\"><span>6<\/span><\/div>\r\n              <h4>Prote\u00e7\u00e3o<\/h4>\r\n              <p>Para-lamas dianteiros e traseiros que permitem uma condu\u00e7\u00e3o mais segura.\r\n            <\/p>\r\n    \r\n          <\/div>\r\n      <\/div>\r\n      <div class=\"element element-7\">\r\n        <div class=\"bike__caixa-mobile\">\r\n          <div class=\"numero\"><span>7<\/span><\/div>\r\n          <h4>Conforto<\/h4>\r\n          <p>Ajuste a altura do selim e do pedal com o conforto de uma bicicleta que se adapta a si.\r\n        <\/p>\r\n    \r\n      <\/div>\r\n      <\/div>\r\n  \r\n  \r\n    <\/div>\r\n    <!-- partial -->\r\n    <script src='https:\/\/cdnjs.cloudflare.com\/ajax\/libs\/jquery\/2.1.3\/jquery.min.js'><\/script>\r\n    <script src='https:\/\/cdn.jsdelivr.net\/jquery.slick\/1.4.1\/slick.min.js'><\/script>\r\n    <script>\r\n      $(\".slick-slider\").slick({\r\n       slidesToShow: 2,\r\n       infinite:true,\r\n       slidesToScroll: 1,\r\n       autoplay: true,\r\n       autoplaySpeed: 6000,\r\n        dots: false, Boolean,\r\n        arrows: false, Boolean,\r\n      });\r\n    \r\n    \r\n    <\/script>\r\n    \r\n    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1cc16634 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1cc16634\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-72c801d0\" data-id=\"72c801d0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3ad7c138 elementor-view-framed elementor-shape-circle elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"3ad7c138\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon elementor-animation-float\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Camada_1\" data-name=\"Camada 1\" viewBox=\"0 0 58.48 58.48\"><defs><style>.cls-1{font-size:66.35px;fill:#e6007e;font-family:MoriGothic-Normal, Mori Gothic;}<\/style><\/defs><text class=\"cls-1\" transform=\"translate(13.84 52.68)\">1<\/text><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tPraticidade\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tCestinha adapt\u00e1vel para o tamanho da bagagem sem acumular \u00e1gua ou sujeira.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-17f440c2 elementor-view-framed elementor-shape-circle elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"17f440c2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon elementor-animation-float\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Camada_1\" data-name=\"Camada 1\" viewBox=\"0 0 58.48 58.48\"><defs><style>.cls-1{font-size:66.35px;fill:#e6007e;font-family:MoriGothic-Normal, Mori Gothic;}<\/style><\/defs><text class=\"cls-1\" transform=\"translate(8.84 52.68)\">3<\/text><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tConforto\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tAjuste a altura do banco e pedale com o conforto de uma bike que se adapta a voc\u00ea.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-34e36d95 elementor-view-framed elementor-shape-circle elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"34e36d95\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon elementor-animation-float\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Camada_1\" data-name=\"Camada 1\" viewBox=\"0 0 58.48 58.48\"><defs><style>.cls-1{font-size:66.35px;fill:#e6007e;font-family:MoriGothic-Normal, Mori Gothic;}<\/style><\/defs><text class=\"cls-1\" transform=\"translate(8.84 52.68)\">5<\/text><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tPraticidade\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tDesbloqueie sua bike por QR code ou pelo app.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-279e12a9 elementor-view-framed elementor-shape-circle elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"279e12a9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon elementor-animation-float\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Camada_1\" data-name=\"Camada 1\" viewBox=\"0 0 58.48 58.48\"><defs><style>.cls-1{font-size:66.35px;fill:#e6007e;font-family:MoriGothic-Normal, Mori Gothic;}<\/style><\/defs><text class=\"cls-1\" transform=\"translate(11.84 52.68)\">7<\/text><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tProte\u00e7\u00e3o\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tCobre-Corrente para mais prote\u00e7\u00e3o ao pedalar.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2b84e3a6\" data-id=\"2b84e3a6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d312ff2 elementor-view-framed elementor-shape-circle elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"d312ff2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon elementor-animation-float\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Camada_1\" data-name=\"Camada 1\" viewBox=\"0 0 58.48 58.48\"><defs><style>.cls-1{font-size:66.35px;fill:#e6007e;font-family:MoriGothic-Normal, Mori Gothic;}<\/style><\/defs><text class=\"cls-1\" transform=\"translate(10.84 52.68)\">2<\/text><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tDesempenho\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tMarcha Shimano Nexus (3 velocidades).\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-69a3617c elementor-view-framed elementor-shape-circle elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"69a3617c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon elementor-animation-float\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Camada_1\" data-name=\"Camada 1\" viewBox=\"0 0 58.48 58.48\"><defs><style>.cls-1{font-size:66.35px;fill:#e6007e;font-family:MoriGothic-Normal, Mori Gothic;}<\/style><\/defs><text class=\"cls-1\" transform=\"translate(9.84 52.68)\">4<\/text><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tSeguran\u00e7a\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tVeja e seja visto com as lanternas de LED que acendem conforme voc\u00ea pedala.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6714251d elementor-view-framed elementor-shape-circle elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"6714251d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon elementor-animation-float\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Camada_1\" data-name=\"Camada 1\" viewBox=\"0 0 58.48 58.48\"><defs><style>.cls-1{font-size:66.35px;fill:#e6007e;font-family:MoriGothic-Normal, Mori Gothic;}<\/style><\/defs><text class=\"cls-1\" transform=\"translate(7.84 52.68)\">6<\/text><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tSeguran\u00e7a\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tSistema de freio \u201cRoller Brake\u201d (freio de rolete), para freadas mais seguras.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5f7da74f elementor-view-framed elementor-shape-circle elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"5f7da74f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon elementor-animation-float\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Camada_1\" data-name=\"Camada 1\" viewBox=\"0 0 58.48 58.48\"><defs><style>.cls-1{font-size:66.35px;fill:#e6007e;font-family:MoriGothic-Normal, Mori Gothic;}<\/style><\/defs><text class=\"cls-1\" transform=\"translate(8.84 52.68)\">8<\/text><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tDesempenho\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tPneus com lados reflexivos e Aro 24.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1712a37e elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1712a37e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-336ad7df\" data-id=\"336ad7df\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3ed35e9 elementor-widget elementor-widget-heading\" data-id=\"3ed35e9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Bicicletas de qualidade internacional dispon\u00edveis sempre que quiser! <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-160e0184 elementor-widget elementor-widget-text-editor\" data-id=\"160e0184\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Conhe\u00e7a mais sobre nossa bici.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bdf69d1 elementor-widget elementor-widget-image\" data-id=\"bdf69d1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"766\" src=\"https:\/\/www.tembici.com.br\/wp-content\/uploads\/2023\/05\/bike-2-1024x766.png\" class=\"attachment-large size-large wp-image-38832\" alt=\"\" srcset=\"https:\/\/www.tembici.com.br\/wp-content\/uploads\/2023\/05\/bike-2-1024x766.png 1024w, https:\/\/www.tembici.com.br\/wp-content\/uploads\/2023\/05\/bike-2-300x225.png 300w, https:\/\/www.tembici.com.br\/wp-content\/uploads\/2023\/05\/bike-2-768x575.png 768w, https:\/\/www.tembici.com.br\/wp-content\/uploads\/2023\/05\/bike-2-1536x1150.png 1536w, https:\/\/www.tembici.com.br\/wp-content\/uploads\/2023\/05\/bike-2-2048x1533.png 2048w, https:\/\/www.tembici.com.br\/wp-content\/uploads\/2023\/05\/bike-2-16x12.png 16w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-33b51868 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"33b51868\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-51e98844\" data-id=\"51e98844\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-746efb53 elementor-view-framed elementor-shape-circle elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"746efb53\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon elementor-animation-float\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Camada_1\" data-name=\"Camada 1\" viewBox=\"0 0 58.48 58.48\"><defs><style>.cls-1{font-size:66.35px;fill:#e6007e;font-family:MoriGothic-Normal, Mori Gothic;}<\/style><\/defs><text class=\"cls-1\" transform=\"translate(13.84 52.68)\">1<\/text><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tPraticidade\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tCestinha adapt\u00e1vel para o tamanho da bagagem sem acumular \u00e1gua ou sujeira.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-466dd0a4 elementor-view-framed elementor-shape-circle elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"466dd0a4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon elementor-animation-float\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Camada_1\" data-name=\"Camada 1\" viewBox=\"0 0 58.48 58.48\"><defs><style>.cls-1{font-size:66.35px;fill:#e6007e;font-family:MoriGothic-Normal, Mori Gothic;}<\/style><\/defs><text class=\"cls-1\" transform=\"translate(10.84 52.68)\">2<\/text><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tDesempenho\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tMarcha Shimano Nexus (3 velocidades).\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5e5c43f2 elementor-view-framed elementor-shape-circle elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"5e5c43f2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon elementor-animation-float\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Camada_1\" data-name=\"Camada 1\" viewBox=\"0 0 58.48 58.48\"><defs><style>.cls-1{font-size:66.35px;fill:#e6007e;font-family:MoriGothic-Normal, Mori Gothic;}<\/style><\/defs><text class=\"cls-1\" transform=\"translate(8.84 52.68)\">3<\/text><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tConforto\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tAjuste a altura do banco e pedale com o conforto de uma bike que se adapta a voc\u00ea.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-20a03cb1 elementor-view-framed elementor-shape-circle elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"20a03cb1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon elementor-animation-float\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Camada_1\" data-name=\"Camada 1\" viewBox=\"0 0 58.48 58.48\"><defs><style>.cls-1{font-size:66.35px;fill:#e6007e;font-family:MoriGothic-Normal, Mori Gothic;}<\/style><\/defs><text class=\"cls-1\" transform=\"translate(9.84 52.68)\">4<\/text><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tSeguran\u00e7a\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tVeja e seja visto com as lanternas de LED que acendem conforme voc\u00ea pedala.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4238ea3d elementor-view-framed elementor-shape-circle elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"4238ea3d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon elementor-animation-float\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Camada_1\" data-name=\"Camada 1\" viewBox=\"0 0 58.48 58.48\"><defs><style>.cls-1{font-size:66.35px;fill:#e6007e;font-family:MoriGothic-Normal, Mori Gothic;}<\/style><\/defs><text class=\"cls-1\" transform=\"translate(8.84 52.68)\">5<\/text><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tPraticidade\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tDesbloqueie sua bike por QR code ou pelo app.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-521031ea elementor-view-framed elementor-shape-circle elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"521031ea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon elementor-animation-float\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Camada_1\" data-name=\"Camada 1\" viewBox=\"0 0 58.48 58.48\"><defs><style>.cls-1{font-size:66.35px;fill:#e6007e;font-family:MoriGothic-Normal, Mori Gothic;}<\/style><\/defs><text class=\"cls-1\" transform=\"translate(7.84 52.68)\">6<\/text><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tSeguran\u00e7a\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tSistema de freio \u201cRoller Brake\u201d (freio de rolete), para freadas mais seguras.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-67584170 elementor-view-framed elementor-shape-circle elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"67584170\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon elementor-animation-float\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Camada_1\" data-name=\"Camada 1\" viewBox=\"0 0 58.48 58.48\"><defs><style>.cls-1{font-size:66.35px;fill:#e6007e;font-family:MoriGothic-Normal, Mori Gothic;}<\/style><\/defs><text class=\"cls-1\" transform=\"translate(11.84 52.68)\">7<\/text><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tProte\u00e7\u00e3o\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tCobre-Corrente para mais prote\u00e7\u00e3o ao pedalar.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2b955e1b elementor-view-framed elementor-hidden-desktop elementor-hidden-tablet elementor-shape-circle elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"2b955e1b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon elementor-animation-float\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Camada_1\" data-name=\"Camada 1\" viewBox=\"0 0 58.48 58.48\"><defs><style>.cls-1{font-size:66.35px;fill:#e6007e;font-family:MoriGothic-Normal, Mori Gothic;}<\/style><\/defs><text class=\"cls-1\" transform=\"translate(8.84 52.68)\">8<\/text><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tDesempenho\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tPneus com lados reflexivos e Aro 24.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4238b360 elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4238b360\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2ca928c3\" data-id=\"2ca928c3\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-74f82865 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"74f82865\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-ef1e84c\" data-id=\"ef1e84c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7e15eafc eael-tooltip-align-left elementor-widget elementor-widget-eael-tooltip\" data-id=\"7e15eafc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"eael-tooltip.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t<div class=\"eael-tooltip\">\n\t\t\t\t\t<span class=\"eael-tooltip-content\" tabindex=\"0\" aria-describedby=\"tooltip-text-7e15eafc\"><img decoding=\"async\" src=\"https:\/\/www.tembici.com.br\/wp-content\/uploads\/2023\/10\/mais.png\" alt=\"\"><\/span>\n  \t\t\t<span id=\"tooltip-text-7e15eafc\" class=\"eael-tooltip-text eael-tooltip-right\" role=\"tooltip\"><p><strong>Prote\u00e7\u00e3o<\/strong><\/p><p><span style=\"font-weight: 400\">Para-lamas dianteiros e traseiros que permitem uma condu\u00e7\u00e3o mais segura.<\/span><\/p><p>.<\/p><\/span>\n  \t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-6da7496b\" data-id=\"6da7496b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ffa981c eael-tooltip-align-left elementor-widget elementor-widget-eael-tooltip\" data-id=\"ffa981c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"eael-tooltip.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t<div class=\"eael-tooltip\">\n\t\t\t\t\t<span class=\"eael-tooltip-content\" tabindex=\"0\" aria-describedby=\"tooltip-text-ffa981c\"><img decoding=\"async\" src=\"https:\/\/www.tembici.com.br\/wp-content\/uploads\/2023\/10\/mais.png\" alt=\"\"><\/span>\n  \t\t\t<span id=\"tooltip-text-ffa981c\" class=\"eael-tooltip-text eael-tooltip-right\" role=\"tooltip\"><p><strong>Conforto<\/strong><\/p><p><span style=\"font-weight: 400\">Ajuste a altura do selim e do pedal com o conforto de uma bicicleta que se adapta a si.<\/span><\/p><\/span>\n  \t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-97c69db eael-tooltip-align-left elementor-widget elementor-widget-eael-tooltip\" data-id=\"97c69db\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"eael-tooltip.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t<div class=\"eael-tooltip\">\n\t\t\t\t\t<span class=\"eael-tooltip-content\" tabindex=\"0\" aria-describedby=\"tooltip-text-97c69db\"><img decoding=\"async\" src=\"https:\/\/www.tembici.com.br\/wp-content\/uploads\/2023\/10\/mais.png\" alt=\"\"><\/span>\n  \t\t\t<span id=\"tooltip-text-97c69db\" class=\"eael-tooltip-text eael-tooltip-right\" role=\"tooltip\"><p><strong>Pot\u00eancia <\/strong><\/p><p><span style=\"font-weight: 400\">Comece a pedalar e conte com o motor da bicicleta para uma dose extra de energia.<\/span><\/p><p><span style=\"font-weight: 400\">.<\/span><\/p><\/span>\n  \t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-388e501b\" data-id=\"388e501b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-799c6d46 eael-tooltip-align-left elementor-widget elementor-widget-eael-tooltip\" data-id=\"799c6d46\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"eael-tooltip.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t<div class=\"eael-tooltip\">\n\t\t\t\t\t<span class=\"eael-tooltip-content\" tabindex=\"0\" aria-describedby=\"tooltip-text-799c6d46\"><img decoding=\"async\" src=\"https:\/\/www.tembici.com.br\/wp-content\/uploads\/2023\/10\/mais.png\" alt=\"\"><\/span>\n  \t\t\t<span id=\"tooltip-text-799c6d46\" class=\"eael-tooltip-text eael-tooltip-right\" role=\"tooltip\"><p><strong>Seguran\u00e7a<\/strong><\/p><p><span style=\"font-weight: 400\">Sistema antivandalismo e rastreado com localiza\u00e7\u00e3o via GPS.<\/span><\/p><\/span>\n  \t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7743483b eael-tooltip-align-left elementor-widget elementor-widget-eael-tooltip\" data-id=\"7743483b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"eael-tooltip.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t<div class=\"eael-tooltip\">\n\t\t\t\t\t<span class=\"eael-tooltip-content\" tabindex=\"0\" aria-describedby=\"tooltip-text-7743483b\"><img decoding=\"async\" src=\"https:\/\/www.tembici.com.br\/wp-content\/uploads\/2023\/10\/mais.png\" alt=\"\"><\/span>\n  \t\t\t<span id=\"tooltip-text-7743483b\" class=\"eael-tooltip-text eael-tooltip-right\" role=\"tooltip\"><p><strong>Praticidade<\/strong><\/p><p><span style=\"font-weight: 400\">Desbloqueie uma bicicleta pelo aplicativo, apontando a c\u00e2mera para o QR Code.<\/span><\/p><\/span>\n  \t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-751bf2c4\" data-id=\"751bf2c4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-39076316 eael-tooltip-align-left elementor-widget elementor-widget-eael-tooltip\" data-id=\"39076316\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"eael-tooltip.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t<div class=\"eael-tooltip\">\n\t\t\t\t\t<span class=\"eael-tooltip-content\" tabindex=\"0\" aria-describedby=\"tooltip-text-39076316\"><img decoding=\"async\" src=\"https:\/\/www.tembici.com.br\/wp-content\/uploads\/2023\/10\/mais.png\" alt=\"\"><\/span>\n  \t\t\t<span id=\"tooltip-text-39076316\" class=\"eael-tooltip-text eael-tooltip-right\" role=\"tooltip\"><p><strong>Conforto<\/strong><\/p><p><span style=\"font-weight: 400\">Transporte at\u00e9 5kg no cesto com el\u00e1stico ajust\u00e1vel.<\/span><\/p><p><br \/>.<\/p><\/span>\n  \t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3c25d9b3 eael-tooltip-align-left elementor-widget elementor-widget-eael-tooltip\" data-id=\"3c25d9b3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"eael-tooltip.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t<div class=\"eael-tooltip\">\n\t\t\t\t\t<span class=\"eael-tooltip-content\" tabindex=\"0\" aria-describedby=\"tooltip-text-3c25d9b3\"><img decoding=\"async\" src=\"https:\/\/www.tembici.com.br\/wp-content\/uploads\/2023\/10\/mais.png\" alt=\"\"><\/span>\n  \t\t\t<span id=\"tooltip-text-3c25d9b3\" class=\"eael-tooltip-text eael-tooltip-right\" role=\"tooltip\"><p><strong>Seguran\u00e7a<\/strong><\/p><p><span style=\"font-weight: 400\">Veja e seja visto com as lanternas de LED que acendem conforme voc\u00ea pedala.<\/span><\/p><\/span>\n  \t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1a856fa7\" data-id=\"1a856fa7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-74b597c3 elementor-widget elementor-widget-heading\" data-id=\"74b597c3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">As melhores bicicletas el\u00e9tricas dispon\u00edveis sempre que voc\u00ea quiser!\n\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-58c09a10 elementor-widget elementor-widget-text-editor\" data-id=\"58c09a10\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Conhe\u00e7a mais sobre a bike Est\u00e1cio.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-09ced43 elementor-section-full_width elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-height-default elementor-section-height-default\" data-id=\"09ced43\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c4a77ef\" data-id=\"c4a77ef\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bdbe142 elementor-widget elementor-widget-text-editor\" data-id=\"bdbe142\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><section class=\"bikes\">\r\n        <div class=\"container\">\r\n            <div class=\"row\">\r\n                <div class=\"col-lg-4\">\r\n                    <h2>Liberdade para ir, vir e curtir com todo o conforto e seguran\u00e7a<\/h2>\r\n                    <p>Conhe\u00e7a\u00a0mais\u00a0sobre\u00a0nossas\u00a0bikes<\/p>\n\r\n                    <div class=\"bikes__menu\">\r\n                        <div class=\"bikes__menu-item active\">\r\n                            <a href=\"#bike-eletrica\">\r\n                                <span class=\"bikes__menu-text\"><i class=\"fas fa-bolt\"><\/i> Bike el\u00e9trica<\/span>\r\n                            <\/a>\r\n                        <\/div>\r\n                        <div class=\"bikes__menu-item\">\r\n                            <a href=\"#bike-normal\">\r\n                                <span class=\"bikes__menu-text\"><i class=\"fas fa-biking\"><\/i> Bike normal<\/span>\r\n                            <\/a>\r\n                        <\/div>\r\n                    <\/div>\r\n                <\/div>\r\n                <div class=\"col-lg-7 offset-lg-1\">\r\n                        <div class=\"change-bike owl-carousel owl-theme\">\r\n                            <div class=\"item\" data-hash=\"bike-eletrica\">\r\n                                <img decoding=\"async\" src=\"https:\/\/www.tembici.com.br\/wp-content\/uploads\/2021\/05\/bike-2.png\">\r\n                            <\/div>\r\n                            <div class=\"item\" data-hash=\"bike-normal\">\r\n                                <img decoding=\"async\" src=\"https:\/\/www.tembici.com.br\/wp-content\/uploads\/2021\/05\/bike-normal2.png\">\r\n                            <\/div>\r\n                        <\/div>\r\n\r\n                    <!-- DESKTOP -->\r\n\r\n                    <div class=\"bike__info bike__info--desktop bike__info--conforto\">\r\n                        <i class=\"fas fa-plus\"><\/i>\r\n                        <div class=\"bike__caixa\">\r\n                            <h4>Conforto<\/h4>\r\n                            <p>Ajuste a altura do banco e pedale com o conforto de uma bike que se adapta a voc\u00ea.<\/p>\n\r\n                        <\/div>\r\n                    <\/div>\r\n                    <div class=\"bike__info bike__info--desktop bike__info--potencia\">\r\n                        <i class=\"fas fa-plus\"><\/i>\r\n                        <div class=\"bike__caixa\">\r\n                            <h4>Pot\u00eancia<\/h4>\r\n                            <p>Comece a pedalar e conte com o motor da bike para ganhar uma dose extra de energia.<\/p>\n\r\n                        <\/div>\r\n                    <\/div>\r\n                    <div class=\"bike__info bike__info--desktop bike__info--praticidade\">\r\n                        <i class=\"fas fa-plus\"><\/i>\r\n                        <div class=\"bike__caixa\">\r\n                            <h4>Praticidade<\/h4>\r\n                            <p>Desbloqueie sua bike com facilidade e aproveite a viagem!<\/p>\n\r\n                        <\/div>\r\n                    <\/div>\r\n                    <div class=\"bike__info bike__info--desktop bike__info--seguranca\">\r\n                        <i class=\"fas fa-plus\"><\/i>\r\n                        <div class=\"bike__caixa\">\r\n                            <h4>Seguran\u00e7a<\/h4>\r\n                            <p>Veja e seja visto com as laternas de LED que acendem conforme voc\u00ea pedala.<\/p>\n\r\n                        <\/div>\r\n                    <\/div>\r\n\r\n                    <!-- MOBILE -->\r\n\r\n                    <div class=\"bike__info bike__info--mobile bike__info--conforto\">\r\n                        <a href=\"#conforto\"><i class=\"fas fa-plus\"><\/i><\/a>\r\n                    <\/div>\r\n                    <div class=\"bike__info bike__info--mobile bike__info--potencia\">\r\n                        <a href=\"#potencia\"><i class=\"fas fa-plus\"><\/i><\/a>\r\n                    <\/div>\r\n                    <div class=\"bike__info bike__info--mobile bike__info--praticidade\">\r\n                        <a href=\"#praticidade\"><i class=\"fas fa-plus\"><\/i><\/a>\r\n                    <\/div>\r\n                    <div class=\"bike__info bike__info--mobile bike__info--seguranca\">\r\n                        <a href=\"#seguranca\"><i class=\"fas fa-plus\"><\/i><\/a>\r\n                    <\/div>\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n        <div class=\"container-fluid-right d-md-none\">\r\n            <div class=\"row\">\r\n                <div class=\"col-12 bike__mobile-menu-wrap\">\r\n                    <div class=\"bike__mobile-menu owl-carousel owl-theme\">\r\n                        <div class=\"item\" data-merge=\"2\">\r\n                            <div class=\"bike__caixa-mobile\" data-hash=\"conforto\">\r\n                                <h4>Conforto<\/h4>\r\n                                <p>Ajuste a altura do banco e pedale com o conforto de uma bike que se adapta a voc\u00ea.<\/p>\n\r\n                            <\/div>\r\n                        <\/div>\r\n                        <div class=\"item\" data-merge=\"2\" data-hash=\"potencia\">\r\n                            <div class=\"bike__caixa-mobile\">\r\n                                <h4>Pot\u00eancia<\/h4>\r\n                                <p>Comece a pedalar e conte com o motor da bike para ganhar uma dose extra de energia.<\/p>\n\r\n                            <\/div>\r\n                        <\/div>\r\n                        <div class=\"item\" data-merge=\"2\" data-hash=\"praticidade\">\r\n                            <div class=\"bike__caixa-mobile\">\r\n                                <h4>Praticidade<\/h4>\r\n                                <p>Desbloqueie sua bike com facilidade e aproveite a viagem!<\/p>\n\r\n                            <\/div>\r\n                        <\/div>\r\n                        <div class=\"item\" data-merge=\"2\" data-hash=\"seguranca\">\r\n                            <div class=\"bike__caixa-mobile\">\r\n                                <h4>Seguran\u00e7a<\/h4>\r\n                                <p>Veja e seja visto com as laternas de LED que acendem conforme voc\u00ea pedala.<\/p>\n\r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/div>\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/section><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-56bdc61 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"56bdc61\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6c78bb23\" data-id=\"6c78bb23\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a596b8d elementor-widget elementor-widget-heading\" data-id=\"a596b8d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Confira onde est\u00e3o nossas esta\u00e7\u00f5es.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-05d413f elementor-widget elementor-widget-text-editor\" data-id=\"05d413f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>J\u00e1 s\u00e3o 51 pontos espalhados por Belo Horizonte, prontos para facilitar seu deslocamento com praticidade e tecnologia.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-500a0a0 elementor-widget elementor-widget-html\" data-id=\"500a0a0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"google-maps\">\n  <iframe src=\"https:\/\/www.google.com\/maps\/d\/embed?mid=1_FaJRa6fe7MEcuNBc-x5uriT6MGZKtM&noprof=1\" width=\"600\" height=\"338\" frameborder=\"0\" style=\"border:0\" allowfullscreen><\/iframe>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-92ff5bc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"92ff5bc\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3d8de488\" data-id=\"3d8de488\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-58f550d5 elementor-widget elementor-widget-text-editor\" data-id=\"58f550d5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Baixe o app e pedale! <\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-104d5ab0 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"104d5ab0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Fa\u00e7a o download para aproveitar as bicis e viver Belo Horizonte de uma maneira diferente.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7336e681 elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"7336e681\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/tembici.onelink.me\/qcBR\/site\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Baixar o app<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-46e72443 elementor-view-stacked elementor-position-inline-start elementor-absolute elementor-hidden-tablet elementor-hidden-phone elementor-shape-circle elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"46e72443\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/api.whatsapp.com\/send?text=J%C3%A1%20viu%20que%20as%20bicis%20da%20Tembici%20chegaram%20em%20Belo%20Horizonte?%20Baixe%20o%20app%20Tembici%20para%20pedalar%20comigo:%20https:\/\/www.tembici.com.br\/pt\/belo-horizonte\/\" target=\"_blank\" class=\"elementor-icon elementor-animation-bob\" tabindex=\"-1\" aria-label=\"Compartilhe e n\u00e3o deixe seus amigos de fora\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-whatsapp\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"https:\/\/api.whatsapp.com\/send?text=J%C3%A1%20viu%20que%20as%20bicis%20da%20Tembici%20chegaram%20em%20Belo%20Horizonte?%20Baixe%20o%20app%20Tembici%20para%20pedalar%20comigo:%20https:\/\/www.tembici.com.br\/pt\/belo-horizonte\/\" target=\"_blank\" >\n\t\t\t\t\t\t\tCompartilhe e n\u00e3o deixe seus amigos de fora\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2a86466e elementor-view-stacked elementor-position-inline-start elementor-hidden-desktop elementor-shape-circle elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"2a86466e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/api.whatsapp.com\/send?text=J%C3%A1%20viu%20que%20as%20bicis%20da%20Tembici%20chegaram%20em%20BH?%20Baixe%20o%20app%20Tembici%20para%20pedalar%20comigo:%20https:\/\/www.tembici.com.br\/pt\/belo-horizonte\/\" target=\"_blank\" class=\"elementor-icon elementor-animation-bob\" tabindex=\"-1\" aria-label=\"Compartilhe e n\u00e3o deixe seus amigos de fora\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-whatsapp\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"https:\/\/api.whatsapp.com\/send?text=J%C3%A1%20viu%20que%20as%20bicis%20da%20Tembici%20chegaram%20em%20BH?%20Baixe%20o%20app%20Tembici%20para%20pedalar%20comigo:%20https:\/\/www.tembici.com.br\/pt\/belo-horizonte\/\" target=\"_blank\" >\n\t\t\t\t\t\t\tCompartilhe e n\u00e3o deixe seus amigos de fora\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7ecdb7b9\" data-id=\"7ecdb7b9\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-146f279b elementor-widget elementor-widget-image\" data-id=\"146f279b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"397\" height=\"530\" src=\"https:\/\/www.tembici.com.br\/wp-content\/uploads\/2024\/02\/BH-Img-Banner-Inferior.png\" class=\"attachment-full size-full wp-image-40116\" alt=\"\" srcset=\"https:\/\/www.tembici.com.br\/wp-content\/uploads\/2024\/02\/BH-Img-Banner-Inferior.png 397w, https:\/\/www.tembici.com.br\/wp-content\/uploads\/2024\/02\/BH-Img-Banner-Inferior-225x300.png 225w, https:\/\/www.tembici.com.br\/wp-content\/uploads\/2024\/02\/BH-Img-Banner-Inferior-9x12.png 9w\" sizes=\"(max-width: 397px) 100vw, 397px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6a9e189 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6a9e189\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b64ec4b\" data-id=\"b64ec4b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d0fe4a1 elementor-widget elementor-widget-html\" data-id=\"d0fe4a1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<style>\n    body {\n    margin:0;\n}\n.eael-pricing.style-1 .eael-pricing-item .price-tag {\n    margin-bottom: 7%!important;\n\n}\n.eael-pricing.style-1 .eael-pricing-item.ribbon-2:after {\n    top: 15px;\n    right: -16px;\n}\n.eael-pricing.style-1 .eael-pricing-item.ribbon-2:before {\n    top: 30px;\n    right: -16px;\n}\n.eael-pricing.style-1 .eael-pricing-item {\n    min-height: 490px;\n    display: flex;\n    flex-direction: column;\n    max-height: 730px;\n    justify-content: space-around;\n}\n.eael-pricing.style-1 .eael-pricing-item .eael-pricing-tag {\n    position: relative;\n    z-index: 0;\n    padding: 0 0px;\n    margin-bottom: 0;\n}\n.trp-language-switcher > div > a {\n    font-family: \"MoriGothic\", Sans-serif;\n    display: block;\n    padding: 4px;\n    border-radius: 3px;\n    color: #fff;\n}\n.card {\n    margin-bottom: 13px;\n    display: flex;\n    height: 33px;\n    padding: 0;\n    border-radius: 9px;\n    background-color: #f90083;\n    margin-top: -47px;\n    flex-direction: column;\n    align-items: center;\n    justify-content: center;\n}\n.card p {\n    letter-spacing: 1px;\n    margin: 0;\n    padding: 0px;\n    font-weight: 600;\n    color: #ffff;\n    font-size: 13px;\n}\n.trp-language-switcher > div {\n    box-sizing: border-box;\n    padding: 1px 1px 1px 26px;\n    border: 1px solid #144bc8;\n    border-radius: 3px;\n    background-image: linear-gradient(45deg, transparent 50%, white 50%),\n            linear-gradient(135deg, white 50%, transparent 50%);\n    background-position: calc(100% - 8px) calc(1em + 0px),\n            calc(100% - 3px) calc(1em + 0px);\n    background-size: 5px 5px,\n            5px 5px;\n    background-repeat: no-repeat;\n    background-color: #144bc8;\n}\n.trp-language-switcher > div > a:hover {\n    background: #144bc8;\n}\n<\/style>\n\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3fcb8049 elementor-section-content-middle elementor-hidden-phone elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3fcb8049\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-61b9edc5\" data-id=\"61b9edc5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-28dfc4ef elementor-widget elementor-widget-image\" data-id=\"28dfc4ef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.tembici.com.br\/wp-content\/uploads\/elementor\/thumbs\/tembici.horizontal.rosa_-1-q781zrnwtoymygj39ccdzn974je26zdv4ox3dnj3cm.png\" title=\"tembici.horizontal.rosa_-1.png\" alt=\"tembici.horizontal.rosa_-1.png\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-7abd7486\" data-id=\"7abd7486\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2a299589 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2a299589\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-2211faf4\" data-id=\"2211faf4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1f743cd3 elementor-widget elementor-widget-heading\" data-id=\"1f743cd3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/help.tembici.com\/\" target=\"_blank\">Fale com a gente<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-aee0b8c\" data-id=\"aee0b8c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1fda40e7 elementor-widget elementor-widget-heading\" data-id=\"1fda40e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/tembicihelp.zendesk.com\/hc\/pt-br\/sections\/24633657640468-Pol%C3%ADticas-e-Termos\" target=\"_blank\">Condi\u00e7\u00f5es Gerais de Uso<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-5dd2dd73\" data-id=\"5dd2dd73\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-42b14b24 elementor-shape-circle e-grid-align-right elementor-grid-0 elementor-widget elementor-widget-social-icons\" data-id=\"42b14b24\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-animation-grow elementor-repeater-item-1bf45d6\" href=\"https:\/\/www.instagram.com\/tembici\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-instagram\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook elementor-animation-grow elementor-repeater-item-0714315\" href=\"https:\/\/www.facebook.com\/tembici\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-facebook\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon- elementor-animation-grow elementor-repeater-item-b72db48\" href=\"https:\/\/twitter.com\/tembici\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\"><\/span>\n\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\"><path d=\"M389.2 48h70.6L305.6 224.2 487 464H345L233.7 318.6 106.5 464H35.8L200.7 275.5 26.8 48H172.4L272.9 180.9 389.2 48zM364.4 421.8h39.1L151.1 88h-42L364.4 421.8z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7acc84d elementor-section-content-middle elementor-hidden-desktop elementor-hidden-tablet elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7acc84d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-217a734a\" data-id=\"217a734a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-23e9da59 elementor-widget elementor-widget-image\" data-id=\"23e9da59\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.tembici.com.br\/wp-content\/uploads\/elementor\/thumbs\/tembici.horizontal.rosa_-1-q781zrnwtoymygj39ccdzn974je26zdv4ox3dnj3cm.png\" title=\"tembici.horizontal.rosa_-1.png\" alt=\"tembici.horizontal.rosa_-1.png\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-5c943acf\" data-id=\"5c943acf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-440037b7 elementor-shape-circle e-grid-align-right elementor-grid-0 elementor-widget elementor-widget-social-icons\" data-id=\"440037b7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-animation-grow elementor-repeater-item-1bf45d6\" href=\"https:\/\/www.instagram.com\/tembici\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-instagram\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook elementor-animation-grow elementor-repeater-item-0714315\" href=\"https:\/\/www.facebook.com\/tembici\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-facebook\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-twitter elementor-animation-grow elementor-repeater-item-b72db48\" href=\"https:\/\/twitter.com\/tembici\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Twitter<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-twitter\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-45dcfcbe\" data-id=\"45dcfcbe\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-42fd5e2a elementor-widget elementor-widget-heading\" data-id=\"42fd5e2a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/help.tembici.com\/\" target=\"_blank\">Fale com a gente<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-20358619 elementor-widget elementor-widget-heading\" data-id=\"20358619\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/tembicihelp.zendesk.com\/hc\/pt-br\/sections\/24633657640468-Pol%C3%ADticas-e-Termos\" target=\"_blank\">Condi\u00e7\u00f5es Gerais de Uso<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Tembici e bike Est\u00e1cio agora est\u00e3o em Belo Horizonte! Est\u00e1cio: a faculdade que move voc\u00ea para todos os lados da cidade. Conecte-se com a energia e a liberdade que s\u00f3 a bike el\u00e9trica pode proporcionar. Para diversos trajetos do seu dia a dia, vai de bike Est\u00e1cio, vai de el\u00e9trica! Em Belo Horizonte todas as [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_canvas","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-39177","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.tembici.com.br\/es\/wp-json\/wp\/v2\/pages\/39177","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tembici.com.br\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.tembici.com.br\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.tembici.com.br\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tembici.com.br\/es\/wp-json\/wp\/v2\/comments?post=39177"}],"version-history":[{"count":147,"href":"https:\/\/www.tembici.com.br\/es\/wp-json\/wp\/v2\/pages\/39177\/revisions"}],"predecessor-version":[{"id":49892,"href":"https:\/\/www.tembici.com.br\/es\/wp-json\/wp\/v2\/pages\/39177\/revisions\/49892"}],"wp:attachment":[{"href":"https:\/\/www.tembici.com.br\/es\/wp-json\/wp\/v2\/media?parent=39177"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}